{"id":8538,"date":"2022-06-30T22:01:38","date_gmt":"2022-06-30T21:01:38","guid":{"rendered":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873.jpg"},"modified":"2022-06-30T22:01:38","modified_gmt":"2022-06-30T21:01:38","slug":"wp-1656622884873-jpg","status":"inherit","type":"attachment","link":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-1656622884873-jpg\/","title":{"rendered":"wp-1656622884873.jpg"},"author":184,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-8538","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"234\" src=\"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-300x234.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-300x234.jpg 300w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-1024x799.jpg 1024w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-768x599.jpg 768w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-1536x1199.jpg 1536w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-2048x1598.jpg 2048w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-984x768.jpg 984w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-1384x1080.jpg 1384w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2136,"height":1667,"file":"2022\/06\/wp-1656622884873.jpg","sizes":{"medium":{"file":"wp-1656622884873-300x234.jpg","width":300,"height":234,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-300x234.jpg"},"large":{"file":"wp-1656622884873-1024x799.jpg","width":1024,"height":799,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-1024x799.jpg"},"thumbnail":{"file":"wp-1656622884873-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-150x150.jpg"},"medium_large":{"file":"wp-1656622884873-768x599.jpg","width":768,"height":599,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-768x599.jpg"},"1536x1536":{"file":"wp-1656622884873-1536x1199.jpg","width":1536,"height":1199,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-1536x1199.jpg"},"2048x2048":{"file":"wp-1656622884873-2048x1598.jpg","width":2048,"height":1598,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-2048x1598.jpg"},"storyform_xlarge":{"file":"wp-1656622884873-984x768.jpg","width":984,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-984x768.jpg"},"storyform_xxlarge":{"file":"wp-1656622884873-1384x1080.jpg","width":1384,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-1384x1080.jpg"},"retina-featured":{"file":"wp-1656622884873-728x455.jpg","width":728,"height":455,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873-728x455.jpg"},"full":{"file":"wp-1656622884873.jpg","width":2136,"height":1667,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873.jpg"}},"image_meta":{"aperture":"1.79","credit":"","camera":"Redmi Note 8T","caption":"","created_timestamp":"1656582493","copyright":"","focal_length":"4.74","iso":"400","shutter_speed":"0.03030303030303","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1656622884873.jpg","_links":{"self":[{"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/media\/8538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/users\/184"}],"replies":[{"embeddable":true,"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/comments?post=8538"}]}}