{"id":8456,"date":"2022-06-19T08:19:15","date_gmt":"2022-06-19T07:19:15","guid":{"rendered":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916.jpg"},"modified":"2022-06-19T08:19:15","modified_gmt":"2022-06-19T07:19:15","slug":"wp-1655623145916-jpg","status":"inherit","type":"attachment","link":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-1655623145916-jpg\/","title":{"rendered":"wp-1655623145916.jpg"},"author":184,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-8456","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"214\" src=\"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-300x214.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-300x214.jpg 300w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-1024x729.jpg 1024w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-768x547.jpg 768w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-1536x1094.jpg 1536w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-1078x768.jpg 1078w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-1516x1080.jpg 1516w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916.jpg 1932w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1932,"height":1376,"file":"2022\/06\/wp-1655623145916.jpg","sizes":{"medium":{"file":"wp-1655623145916-300x214.jpg","width":300,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-300x214.jpg"},"large":{"file":"wp-1655623145916-1024x729.jpg","width":1024,"height":729,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-1024x729.jpg"},"thumbnail":{"file":"wp-1655623145916-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-150x150.jpg"},"medium_large":{"file":"wp-1655623145916-768x547.jpg","width":768,"height":547,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-768x547.jpg"},"1536x1536":{"file":"wp-1655623145916-1536x1094.jpg","width":1536,"height":1094,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-1536x1094.jpg"},"storyform_xlarge":{"file":"wp-1655623145916-1078x768.jpg","width":1078,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-1078x768.jpg"},"storyform_xxlarge":{"file":"wp-1655623145916-1516x1080.jpg","width":1516,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-1516x1080.jpg"},"retina-featured":{"file":"wp-1655623145916-728x455.jpg","width":728,"height":455,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916-728x455.jpg"},"full":{"file":"wp-1655623145916.jpg","width":1932,"height":1376,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916.jpg"}},"image_meta":{"aperture":"1.79","credit":"","camera":"Redmi Note 8T","caption":"","created_timestamp":"1655375745","copyright":"","focal_length":"4.74","iso":"125","shutter_speed":"0.00031585596967783","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/06\/wp-1655623145916.jpg","_links":{"self":[{"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/media\/8456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/users\/184"}],"replies":[{"embeddable":true,"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/comments?post=8456"}]}}