{"id":10504,"date":"2022-11-17T23:28:55","date_gmt":"2022-11-17T22:28:55","guid":{"rendered":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585.jpg"},"modified":"2022-11-17T23:28:55","modified_gmt":"2022-11-17T22:28:55","slug":"wp-1668724116585-jpg","status":"inherit","type":"attachment","link":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-1668724116585-jpg\/","title":{"rendered":"wp-1668724116585.jpg"},"author":184,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-10504","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"188\" src=\"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-300x188.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-300x188.jpg 300w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-1024x640.jpg 1024w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-768x480.jpg 768w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-1228x768.jpg 1228w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-728x455.jpg 728w, https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585.jpg 1511w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1511,"height":945,"file":"2022\/11\/wp-1668724116585.jpg","sizes":{"medium":{"file":"wp-1668724116585-300x188.jpg","width":300,"height":188,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-300x188.jpg"},"large":{"file":"wp-1668724116585-1024x640.jpg","width":1024,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-1024x640.jpg"},"thumbnail":{"file":"wp-1668724116585-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-150x150.jpg"},"medium_large":{"file":"wp-1668724116585-768x480.jpg","width":768,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-768x480.jpg"},"storyform_xlarge":{"file":"wp-1668724116585-1228x768.jpg","width":1228,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-1228x768.jpg"},"retina-featured":{"file":"wp-1668724116585-728x455.jpg","width":728,"height":455,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585-728x455.jpg"},"full":{"file":"wp-1668724116585.jpg","width":1511,"height":945,"mime_type":"image\/jpeg","source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-content\/uploads\/sites\/128\/2022\/11\/wp-1668724116585.jpg","_links":{"self":[{"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/media\/10504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/users\/184"}],"replies":[{"embeddable":true,"href":"https:\/\/blogak.goiena.eus\/sasoibide\/wp-json\/wp\/v2\/comments?post=10504"}]}}